{"id":3684,"date":"2025-07-16T06:45:34","date_gmt":"2025-07-16T04:45:34","guid":{"rendered":"https:\/\/www.nbi-ngf.ch\/?page_id=3684"},"modified":"2026-03-24T14:31:53","modified_gmt":"2026-03-24T13:31:53","slug":"histoere","status":"publish","type":"page","link":"https:\/\/www.nbi-ngf.ch\/fr\/a-propos-de-nous\/facts-figures\/histoere\/","title":{"rendered":"Histoire"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3684\" class=\"elementor elementor-3684 elementor-959\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9127068 e-con-full header-container e-flex e-con e-parent\" data-id=\"9127068\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t<div class=\"elementor-element elementor-element-b6b9835 e-con-full e-flex e-con e-child\" data-id=\"b6b9835\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e6b0354 e-con-full header-text e-flex e-con e-child\" data-id=\"e6b0354\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-be394aa elementor-align-left elementor-widget elementor-widget-breadcrumbs\" data-id=\"be394aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span class=\"breadcrumb-item\">Home<\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c91cc3 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"2c91cc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Histoire<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-98a6d41 anchor-menu e-flex e-con-boxed e-con e-parent\" data-id=\"98a6d41\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;sticky_offset&quot;:90,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-27a06c7 elementor-widget elementor-widget-button\" data-id=\"27a06c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#histoire\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Histoire<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2c7861cd e-flex e-con-boxed e-con e-parent\" data-id=\"2c7861cd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c4f06d1 elementor-widget elementor-widget-spacer\" data-id=\"1c4f06d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-30b714c e-flex e-con-boxed e-con e-parent\" data-id=\"30b714c\" data-element_type=\"container\" data-e-type=\"container\" id=\"histoire\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8ffb532 e-con-full e-flex e-con e-child\" data-id=\"8ffb532\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-995b718 elementor-widget elementor-widget-heading\" data-id=\"995b718\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Histoire<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-02d87c3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"02d87c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f37a6ce elementor-widget elementor-widget-image\" data-id=\"f37a6ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.nbi-ngf.ch\/wp-content\/uploads\/2026\/03\/Geschichte_nbi-ngf_2026_F-1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"Geschichte_nbi-ngf_2026_F\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODgzNCwidXJsIjoiaHR0cHM6XC9cL3d3dy5uYmktbmdmLmNoXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI2XC8wM1wvR2VzY2hpY2h0ZV9uYmktbmdmXzIwMjZfRi0xLmpwZyJ9\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"595\" height=\"842\" src=\"https:\/\/www.nbi-ngf.ch\/wp-content\/uploads\/2026\/03\/Geschichte_nbi-ngf_2026_F-1.jpg\" class=\"attachment-large size-large wp-image-8834\" alt=\"\" srcset=\"https:\/\/www.nbi-ngf.ch\/wp-content\/uploads\/2026\/03\/Geschichte_nbi-ngf_2026_F-1.jpg 595w, https:\/\/www.nbi-ngf.ch\/wp-content\/uploads\/2026\/03\/Geschichte_nbi-ngf_2026_F-1-212x300.jpg 212w\" sizes=\"(max-width: 595px) 100vw, 595px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e9178a e-con-full e-flex e-con e-child\" data-id=\"6e9178a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-375a9ca e-flex e-con-boxed e-con e-parent\" data-id=\"375a9ca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-daf75df elementor-widget elementor-widget-spacer\" data-id=\"daf75df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1f5f7d76 e-flex e-con-boxed e-con e-parent\" data-id=\"1f5f7d76\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-329f29c4 e-con-full e-flex e-con e-child\" data-id=\"329f29c4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6df26d2a akkordeon elementor-widget elementor-widget-n-accordion\" data-id=\"6df26d2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1840\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1840\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Conventions de ZURICH  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1840\" class=\"elementor-element elementor-element-5fc35c1d e-con-full e-flex e-con e-child\" data-id=\"5fc35c1d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1840\" class=\"elementor-element elementor-element-11d8ecdf e-flex e-con-boxed e-con e-child\" data-id=\"11d8ecdf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5aeac15b elementor-widget elementor-widget-text-editor\" data-id=\"5aeac15b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le FNG a sign\u00e9 des accords avec les Fonds de Garantie des Etats membres de l\u2019EEE en vue d\u2019am\u00e9liorer la protection des l\u00e9s\u00e9s au sein de l\u2019Espace Economique Europ\u00e9en et en Suisse.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d54e11 btn_60 elementor-widget elementor-widget-button\" data-id=\"6d54e11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.nbi-ngf.ch\/fr\/gestion-des-sinistres\/conventions-internationales\/conventions-internationales-des-fonds-de-garantie\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Conventions des Fonds de Garantie<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1841\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1841\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> La vignette pour v\u00e9los en Suisse  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1841\" class=\"elementor-element elementor-element-20e62334 e-con-full e-flex e-con e-child\" data-id=\"20e62334\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1841\" class=\"elementor-element elementor-element-69242718 e-flex e-con-boxed e-con e-child\" data-id=\"69242718\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-62758dae elementor-widget elementor-widget-text-editor\" data-id=\"62758dae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La vignette obligatoire pour v\u00e9los, qui, en cas d\u2019accident, couvrait la responsabilit\u00e9 de l\u2019utilisateur du v\u00e9lo, a \u00e9t\u00e9 supprim\u00e9e \u00e0 partir du 1.1.2012. Les v\u00e9los \u00e9quip\u00e9s d&rsquo;une assistance \u00e9lectrique jusqu&rsquo;\u00e0 25 km\/h, les voitures \u00e0 bras \u00e9quip\u00e9es d&rsquo;un moteur, certains monoaxes et fauteuils roulants \u00e9lectriques jusqu&rsquo;\u00e0 10 km\/h ne doivent \u00e9galement plus \u00eatre munis de vignette.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1842\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1842\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> L'Origine du syst\u00e8me de la Carte verte <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1842\" class=\"elementor-element elementor-element-3166946d e-con-full e-flex e-con e-child\" data-id=\"3166946d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1842\" class=\"elementor-element elementor-element-563730ae e-flex e-con-boxed e-con e-child\" data-id=\"563730ae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-73aad588 elementor-widget elementor-widget-text-editor\" data-id=\"73aad588\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Recommandation n\u00b0 5 \u00e9labor\u00e9e en 1949 par les Nations-Unies \u00e0 Gen\u00e8ve (commission \u00e9conomique pour l&rsquo;Europe, sous-comit\u00e9 de la circulation routi\u00e8re) invitait les gouvernements des pays europ\u00e9ens \u00e0 adopter des normes uniformes pour que les victimes d&rsquo;accidents de la circulation, dans lesquels est engag\u00e9e la responsabilit\u00e9 civile d&rsquo;un automobiliste \u00e9tranger, b\u00e9n\u00e9ficient d&rsquo;une protection suffisante. Il s&rsquo;agissait donc d&rsquo;am\u00e9liorer la protection des victimes nationales d&rsquo;accidents de la circulation face \u00e0 des personnes responsables \u00e9trang\u00e8res. Il s&rsquo;agissait de ne plus obliger les victimes d&rsquo;accidents de la circulation \u00e0 faire valoir leurs droits \u00e0 l&rsquo;\u00e9tranger. Deux \u00e9l\u00e9ments particuliers devaient \u00eatre pris en consid\u00e9ration. D&rsquo;une part, le fait que l&rsquo;accident ait \u00e9t\u00e9 caus\u00e9 par un v\u00e9hicule \u00e9tranger ne devait pas d\u00e9savantager la personne l\u00e9s\u00e9e (protection des victimes). D&rsquo;autre part, les automobilistes ne devaient pas \u00eatre retard\u00e9s au passage de la fronti\u00e8re par de longues formalit\u00e9s douani\u00e8res, au motif qu&rsquo;ils devaient satisfaire, au moment d&rsquo;entrer dans le pays, aux obligations de ce pays en mati\u00e8re d&rsquo;assurance.<\/p><p>Les Etats membres de la commission des Nations Unies pour l&rsquo;Europe ont fond\u00e9 des Bureaux Nationaux d&rsquo;Assurance pour suivre la Recommandation n\u00b0 5. Ces bureaux, reconnus par les gouvernements, sont d&rsquo;une part responsable de l&rsquo;\u00e9mission de cartes internationales d&rsquo;assurance automobile &#8211; la\u00a0Carte verte &#8211;\u00a0\u00a0\u00a0qui attestent une couverture d&rsquo;assurance responsabilit\u00e9 civile suffisante lors de l&rsquo;entr\u00e9e du v\u00e9hicule dans d&rsquo;autres\u00a0Etats membres. D&rsquo;autre part, ils sont responsables de la couverture des dommages caus\u00e9s par des v\u00e9hicules en provenance d&rsquo;autres Etats membres et disposant d&rsquo;une telle carte d&rsquo;assurance. Le syst\u00e8me de la carte verte a donc permis d&rsquo;uniformiser les crit\u00e8res exig\u00e9s en mati\u00e8re d&rsquo;assurance au passage de la fronti\u00e8re et d&rsquo;harmoniser le r\u00e8glement transfrontalier des sinistres en Europe.<\/p><p>Les Bureaux Nationaux d&rsquo;Assurance ont\u00a0fond\u00e9 l&rsquo;organisation fa\u00eeti\u00e8re CdB &#8211; le\u00a0Conseil des Bureaux &#8211;\u00a0\u00a0 et conclu divers accords afin de mettre en pratique les principes de la Recommandation n\u00b0 5.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1843\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1843\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> La Convention de Londres <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1843\" class=\"elementor-element elementor-element-5a51e52 e-con-full e-flex e-con e-child\" data-id=\"5a51e52\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1843\" class=\"elementor-element elementor-element-d8faf0c e-flex e-con-boxed e-con e-child\" data-id=\"d8faf0c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-97ecde2 elementor-widget elementor-widget-text-editor\" data-id=\"97ecde2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Afin de r\u00e9aliser le syst\u00e8me de la Carte verte, le Conseil des bureaux \u00e0\u00a0\u00e9labor\u00e9\u00a0une convention\u00a0entre bureaux, qui porte le nom de son origine \u00ab\u00a0Convention de Londres\u00a0\u00bb. La Convention de Londres se base sur les principes g\u00e9n\u00e9raux suivants.<\/p><p>Les assureurs RC automobile constituent dans chaque pays un bureau national d&rsquo;assurance. Ils sont membres de cet organisme central. Le bureau national d&rsquo;assurance fait l&rsquo;objet de l&rsquo;agr\u00e9ment par le gouvernement de son pays. Ce bureau national d&rsquo;assurance a pour l&rsquo;essentiel une double fonction:<\/p><ul><li>C&rsquo;est dans sa fonction de \u00ab\u00a0bureau garant\u00a0\u00bb que le bureau national d&rsquo;assurance d\u00e9livre aux assur\u00e9s, par l&rsquo;interm\u00e9diaire de ses membres, la carte verte, document d&rsquo;assurance international standard. Le bureau garant est responsable du respect des engagements vis-\u00e0-vis du \u00ab\u00a0bureau g\u00e9rant\u00a0\u00bb, et est soumis \u00e0 une responsabilit\u00e9 subsidiaire, aux c\u00f4t\u00e9s de l&rsquo;assureur, en ce qui concerne les obligations d\u00e9coulant du contrat de ce dernier ou d\u00e9coulant de la carte verte et des conventions d&rsquo;assurance.<\/li><li>Dans sa fonction de \u00ab\u00a0bureau g\u00e9rant\u00a0\u00bb, le bureau national d&rsquo;assurance r\u00e8gle de fa\u00e7on g\u00e9n\u00e9rale les sinistres transfrontaliers en responsabilit\u00e9 civile caus\u00e9s sur son territoire par des v\u00e9hicules \u00e9trangers munis de la carte verte ou relevant de la Convention d&rsquo;immatriculation. Pour le r\u00e8glement du sinistre, il applique les dispositions contenues dans les conventions internationales d&rsquo;assurance et celles contenues dans sa l\u00e9gislation nationale. En cas de sinistre, c&rsquo;est le bureau du pays visit\u00e9 qui doit proc\u00e9der au r\u00e8glement et garantir au demandeur que l&rsquo;assureur &#8211; dans la mesure o\u00f9 la cr\u00e9ance est justifi\u00e9e &#8211; effectue l&rsquo;indemnisation.<\/li><\/ul><p>La Carte verte garantit, par l&rsquo;interm\u00e9diaire du bureau national d&rsquo;assurance \u00e9metteur, que l&rsquo;assur\u00e9 b\u00e9n\u00e9ficie \u00e0 l&rsquo;\u00e9tranger d&rsquo;une couverture d&rsquo;assurance suffisante. Cela signifie qu&rsquo;en cas de sinistre, ce document lui garantit une protection correspondant au montant minimum de couverture en responsabilit\u00e9 civile en vigueur dans le pays visit\u00e9 \u00e0 la date de l&rsquo;accident. Les \u00c9tats membres reconnaissent la Carte verte au m\u00eame titre qu&rsquo;une police d&rsquo;assurance.<\/p><p>Les bureaux se garantissent mutuellement le remboursement des d\u00e9penses li\u00e9es au r\u00e8glement des sinistres. Le bureau \u00e9metteur de la Carte verte doit garantir le remboursement de tous les co\u00fbts li\u00e9s au sinistre sous r\u00e9serve de pr\u00e9sentation des justificatifs correspondants. Ce sont toutefois ses membres (les assureurs) qui doivent en premi\u00e8re ligne satisfaire \u00e0 ces obligations. Le remboursement effectu\u00e9 au \u00ab\u00a0bureau g\u00e9rant\u00a0\u00bb se compose de l&rsquo;indemnisation vers\u00e9e, des frais externes li\u00e9s au r\u00e8glement du sinistre, de m\u00eame que des honoraires de gestion du dossier dont le montant pr\u00e9cis est fix\u00e9 par le Conseil des Bureaux (CdB) et qui est cens\u00e9 couvrir tous les autres frais. Le remboursement ne couvre donc pas seulement l&rsquo;indemnisation des dommages, mais comporte aussi une taxe pour couvrir les frais de gestion du dossier.<\/p><p>De nos jours, tous les bureaux nationaux sont \u00e9galement membres d&rsquo;une organisation supranationale, le Conseil des Bureaux (CdB). Ce dernier garantit le bon fonctionnement du syst\u00e8me de la Carte verte. Son secr\u00e9tariat se trouve \u00e0 Bruxelles.<\/p><p>La Convention de Londres est remplac\u00e9e depuis le 1.7.2003 par le R\u00e8glement G\u00e9n\u00e9ral.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-524fcc4 btn_60 elementor-widget elementor-widget-button\" data-id=\"524fcc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.nbi-ngf.ch\/fr\/gestion-des-sinistres\/grenzuberschreitender-verkehr\/carte-dassurance-internationale\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">La Carte d'assurance internationale<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-879f3ef btn_60 elementor-widget elementor-widget-button\" data-id=\"879f3ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.nbi-ngf.ch\/fr\/a-propos-de-nous\/europe\/organisation-faitiere-cob\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\"> Organisation fa\u00eeti\u00e8re COB<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1844\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1844\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> La Convention multilat\u00e9rale de garantie <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1844\" class=\"elementor-element elementor-element-a83dead e-con-full e-flex e-con e-child\" data-id=\"a83dead\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1844\" class=\"elementor-element elementor-element-23ed379 e-flex e-con-boxed e-con e-child\" data-id=\"23ed379\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ab1fca4 elementor-widget elementor-widget-text-editor\" data-id=\"ab1fca4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dans la \u00ab\u00a0Convention multilat\u00e9rale de garantie entre bureaux nationaux d&rsquo;assureurs\u00a0\u00bb, appel\u00e9e aussi \u00ab\u00a0convention d&rsquo;immatriculation\u00a0\u00bb ou encore \u00ab\u00a0convention des plaques\u00a0\u00bb, l&rsquo;immatriculation du v\u00e9hicule remplace la Carte verte en tant qu&rsquo;attestation d&rsquo;assurance \u00e0 l&rsquo;\u00e9tranger. Au fil du temps, les \u00e9tats sont devenus de plus en plus nombreux \u00e0 soumettre l&rsquo;immatriculation d&rsquo;un v\u00e9hicule \u00e0 la condition de la pr\u00e9sentation d&rsquo;une attestation d&rsquo;assurance en responsabilit\u00e9 civile. De cette mani\u00e8re, l&rsquo;automobiliste n&rsquo;avait plus besoin d&rsquo;une attestation d&rsquo;assurance suppl\u00e9mentaire. C&rsquo;est la raison pour laquelle de nombreux \u00e9tats ont cess\u00e9 de contr\u00f4ler la d\u00e9tention de la carte verte.<\/p><p>La directive CE de 1972 a reconnu cet \u00e9tat de fait et d\u00e9cid\u00e9 que la Carte verte n&rsquo;\u00e9tait plus obligatoire pour les v\u00e9hicules ayant leur stationnement habituel dans un \u00e9tat membre et se rendant dans autre \u00e9tat membre. Cette directive communautaire a servi de base pour l&rsquo;\u00e9laboration de la Convention multilat\u00e9rale de garantie qui s&rsquo;applique aujourd&rsquo;hui \u00e0 tous les pays de l&rsquo;UE (plus ceux de l&rsquo;EEE), Andorre, Monaco, San Marino, la Serbie, Bosnie et Herz\u00e9govine, Mont\u00e9n\u00e9gro, Grande-Bretagne, le Vatican et la Suisse.<\/p><p>Aux termes de cette Convention, est consid\u00e9r\u00e9 de fa\u00e7on g\u00e9n\u00e9rale comme \u00ab\u00a0pays dans lequel le v\u00e9hicule a son lieu habituel de stationnement\u00a0\u00bb le \u00ab\u00a0territoire du pays dont le v\u00e9hicule porte l&rsquo;immatriculation officielle\u00a0\u00bb. Cette d\u00e9finition est importante car, pour que la Convention multilat\u00e9rale de garantie s&rsquo;applique, le v\u00e9hicule doit avoir son lieu de stationnement habituel dans un pays dont le bureau national est partie \u00e0 la Convention. Cette convention est, comme son nom l&rsquo;indique, d&rsquo;application multilat\u00e9rale entre les pays signataires.<\/p><p>La Convention multilat\u00e9rale de garantie a \u00e9t\u00e9 sign\u00e9e le 15 mars 1991 et s&rsquo;appliquait aux sinistres survenus apr\u00e8s le 1er juin 1991. Les principes de cette Convention restent applicables dans le cadre de la nouvelle Convention, le R\u00e8glement G\u00e9n\u00e9ral, entr\u00e9 en vigueur le 1.7.2003.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1845\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"6\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1845\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> La Convention sur les fausses plaques d'immatriculation <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1845\" class=\"elementor-element elementor-element-5bc9e38 e-con-full e-flex e-con e-child\" data-id=\"5bc9e38\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1845\" class=\"elementor-element elementor-element-953ba1c e-flex e-con-boxed e-con e-child\" data-id=\"953ba1c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d977222 elementor-widget elementor-widget-text-editor\" data-id=\"d977222\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le 1er octobre 1993 est entr\u00e9e en vigueur la Convention officielle \u00ab\u00a0sur les fausses plaques d&rsquo;immatriculation\u00a0\u00bb, ratifi\u00e9e par tous les Bureaux signataires de la Convention multilat\u00e9rale de garantie. Lorsque la plaque d&rsquo;immatriculation d&rsquo;un v\u00e9hicule \u00e9tait fausse ou falsifi\u00e9e, le pays comp\u00e9tent \u00e9tait celui ayant proc\u00e9d\u00e9 \u00e0 la derni\u00e8re immatriculation r\u00e9guli\u00e8re. \u00a0C&rsquo;\u00e9tait la r\u00e8gle en vigueur jusqu&rsquo;\u00e0 fin juin 2003. Depuis le 1er juillet 2003, s&rsquo;applique l&rsquo;art. 11.2 du R\u00e8glement G\u00e9n\u00e9ral qui veut que, pour les fausses plaques d&rsquo;immatriculation, soit consid\u00e9r\u00e9 comme lieu de stationnement habituel du v\u00e9hicule le lieu de l&rsquo;accident, de sorte que l&rsquo;obligation de couverture revient au fonds de garantie du pays de l&rsquo;accident.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1846\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"7\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1846\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Le R\u00e8glement G\u00e9n\u00e9ral  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1846\" class=\"elementor-element elementor-element-1155975 e-con-full e-flex e-con e-child\" data-id=\"1155975\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1846\" class=\"elementor-element elementor-element-0f0adfb e-flex e-con-boxed e-con e-child\" data-id=\"0f0adfb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b0b0cc elementor-widget elementor-widget-text-editor\" data-id=\"7b0b0cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>C&rsquo;est le 1er juillet 2003 qu&rsquo;est entr\u00e9 en vigueur le R\u00e8glement G\u00e9n\u00e9ral, adopt\u00e9 par l&rsquo;Assembl\u00e9e g\u00e9n\u00e9rale du Conseil des Bureaux (CdB) en 2002. Il remplace la Convention de Londres et la Convention multilat\u00e9rale de garantie et pr\u00e9voit des r\u00e8gles uniformes pour la coop\u00e9ration entre bureaux nationaux. Les principes de l&rsquo;ancienne Convention se retrouvent dans la nouvelle.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6743ba btn_60 elementor-widget elementor-widget-button\" data-id=\"a6743ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.nbi-ngf.ch\/fr\/gestion-des-sinistres\/conventions-internationales\/reglement-general\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">R\u00e8glement G\u00e9n\u00e9ral<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1847\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"8\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1847\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Les conventions de protection des visiteurs <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1847\" class=\"elementor-element elementor-element-cc21f42 e-con-full e-flex e-con e-child\" data-id=\"cc21f42\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1847\" class=\"elementor-element elementor-element-fb10f07 e-flex e-con-boxed e-con e-child\" data-id=\"fb10f07\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-809ebb6 elementor-widget elementor-widget-text-editor\" data-id=\"809ebb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un jalon suppl\u00e9mentaire en mati\u00e8re de protection des victimes d&rsquo;accidents de la circulation est constitu\u00e9 par les conventions de protection des visiteurs que la Suisse, ou plus pr\u00e9cis\u00e9ment le Bureau National Suisse d&rsquo;Assurance (BNA), a conclu depuis le 1er f\u00e9vrier 2003 avec tous les pays appartenant \u00e0 l&rsquo;EEE. Ces accords conf\u00e8rent \u00e0 une personne victime d&rsquo;un accident de la circulation \u00e0 l&rsquo;\u00e9tranger (visiteur) la possibilit\u00e9 de faire indemniser le sinistre dont la r\u00e9paration incombe \u00e0 un assureur responsabilit\u00e9 civile \u00e9tranger par le repr\u00e9sentant de ce dernier dans son pays de domicile. Ce repr\u00e9sentant proc\u00e8de au r\u00e8glement du sinistre conform\u00e9ment \u00e0 la l\u00e9gislation du pays de l&rsquo;accident et selon les instructions de l&rsquo;assureur \u00e9tranger.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6a99d5 btn_60 elementor-widget elementor-widget-button\" data-id=\"d6a99d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.nbi-ngf.ch\/fr\/gestion-des-sinistres\/conventions-internationales\/protection-des-visiteurs\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Protection des visiteurs<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2921448f e-con-full e-flex e-con e-child\" data-id=\"2921448f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-28200b4 e-flex e-con-boxed e-con e-parent\" data-id=\"28200b4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-41a3573 elementor-widget elementor-widget-spacer\" data-id=\"41a3573\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ee89e40 e-flex e-con-boxed e-con e-parent\" data-id=\"ee89e40\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-57a6832 elementor-widget elementor-widget-spacer\" data-id=\"57a6832\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bf583b1 e-flex e-con-boxed e-con e-parent\" data-id=\"bf583b1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Histoire Histoire Conventions de ZURICH Le FNG a sign\u00e9 des accords avec les Fonds de Garantie des Etats membres de l\u2019EEE en vue d\u2019am\u00e9liorer la protection des l\u00e9s\u00e9s au sein de l\u2019Espace Economique Europ\u00e9en et en Suisse. Conventions des Fonds de Garantie La vignette pour v\u00e9los en Suisse La vignette obligatoire pour v\u00e9los, qui, en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":3620,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3684","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire - Nationales Versicherungsb\u00fcro | Nationaler Garantiefonds<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nbi-ngf.ch\/fr\/a-propos-de-nous\/facts-figures\/histoere\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire - Nationales Versicherungsb\u00fcro | Nationaler Garantiefonds\" \/>\n<meta property=\"og:description\" content=\"Histoire Histoire Conventions de ZURICH Le FNG a sign\u00e9 des accords avec les Fonds de Garantie des Etats membres de l\u2019EEE en vue d\u2019am\u00e9liorer la protection des l\u00e9s\u00e9s au sein de l\u2019Espace Economique Europ\u00e9en et en Suisse. Conventions des Fonds de Garantie La vignette pour v\u00e9los en Suisse La vignette obligatoire pour v\u00e9los, qui, en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nbi-ngf.ch\/fr\/a-propos-de-nous\/facts-figures\/histoere\/\" \/>\n<meta property=\"og:site_name\" content=\"Nationales Versicherungsb\u00fcro | Nationaler Garantiefonds\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-24T13:31:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nbi-ngf.ch\/wp-content\/uploads\/2026\/03\/Geschichte_nbi-ngf_2026_F-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nbi-ngf.ch\\\/fr\\\/a-propos-de-nous\\\/facts-figures\\\/histoere\\\/\",\"url\":\"https:\\\/\\\/www.nbi-ngf.ch\\\/fr\\\/a-propos-de-nous\\\/facts-figures\\\/histoere\\\/\",\"name\":\"Histoire - Nationales Versicherungsb\u00fcro | Nationaler Garantiefonds\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nbi-ngf.ch\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nbi-ngf.ch\\\/fr\\\/a-propos-de-nous\\\/facts-figures\\\/histoere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nbi-ngf.ch\\\/fr\\\/a-propos-de-nous\\\/facts-figures\\\/histoere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nbi-ngf.ch\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Geschichte_nbi-ngf_2026_F-1.jpg\",\"datePublished\":\"2025-07-16T04:45:34+00:00\",\"dateModified\":\"2026-03-24T13:31:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nbi-ngf.ch\\\/fr\\\/a-propos-de-nous\\\/facts-figures\\\/histoere\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nbi-ngf.ch\\\/fr\\\/a-propos-de-nous\\\/facts-figures\\\/histoere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.nbi-ngf.ch\\\/fr\\\/a-propos-de-nous\\\/facts-figures\\\/histoere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.nbi-ngf.ch\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Geschichte_nbi-ngf_2026_F-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nbi-ngf.ch\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Geschichte_nbi-ngf_2026_F-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nbi-ngf.ch\\\/fr\\\/a-propos-de-nous\\\/facts-figures\\\/histoere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.nbi-ngf.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c0 propos de nous\",\"item\":\"https:\\\/\\\/www.nbi-ngf.ch\\\/fr\\\/a-propos-de-nous\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Facts &amp; Figures\",\"item\":\"https:\\\/\\\/www.nbi-ngf.ch\\\/fr\\\/a-propos-de-nous\\\/facts-figures\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Histoire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nbi-ngf.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.nbi-ngf.ch\\\/fr\\\/\",\"name\":\"Nationales Versicherungsb\u00fcro | Nationaler Garantiefonds\",\"description\":\"Schweiz\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nbi-ngf.ch\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nbi-ngf.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nbi-ngf.ch\\\/fr\\\/#organization\",\"name\":\"Nationales Versicherungsb\u00fcro | Nationaler Garantiefonds\",\"url\":\"https:\\\/\\\/www.nbi-ngf.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.nbi-ngf.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nbi-ngf.ch\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Logo-Nbi-Ngf.svg\",\"contentUrl\":\"https:\\\/\\\/www.nbi-ngf.ch\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Logo-Nbi-Ngf.svg\",\"caption\":\"Nationales Versicherungsb\u00fcro | Nationaler Garantiefonds\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nbi-ngf.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire - Nationales Versicherungsb\u00fcro | Nationaler Garantiefonds","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nbi-ngf.ch\/fr\/a-propos-de-nous\/facts-figures\/histoere\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire - Nationales Versicherungsb\u00fcro | Nationaler Garantiefonds","og_description":"Histoire Histoire Conventions de ZURICH Le FNG a sign\u00e9 des accords avec les Fonds de Garantie des Etats membres de l\u2019EEE en vue d\u2019am\u00e9liorer la protection des l\u00e9s\u00e9s au sein de l\u2019Espace Economique Europ\u00e9en et en Suisse. Conventions des Fonds de Garantie La vignette pour v\u00e9los en Suisse La vignette obligatoire pour v\u00e9los, qui, en [&hellip;]","og_url":"https:\/\/www.nbi-ngf.ch\/fr\/a-propos-de-nous\/facts-figures\/histoere\/","og_site_name":"Nationales Versicherungsb\u00fcro | Nationaler Garantiefonds","article_modified_time":"2026-03-24T13:31:53+00:00","og_image":[{"url":"https:\/\/www.nbi-ngf.ch\/wp-content\/uploads\/2026\/03\/Geschichte_nbi-ngf_2026_F-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.nbi-ngf.ch\/fr\/a-propos-de-nous\/facts-figures\/histoere\/","url":"https:\/\/www.nbi-ngf.ch\/fr\/a-propos-de-nous\/facts-figures\/histoere\/","name":"Histoire - Nationales Versicherungsb\u00fcro | Nationaler Garantiefonds","isPartOf":{"@id":"https:\/\/www.nbi-ngf.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nbi-ngf.ch\/fr\/a-propos-de-nous\/facts-figures\/histoere\/#primaryimage"},"image":{"@id":"https:\/\/www.nbi-ngf.ch\/fr\/a-propos-de-nous\/facts-figures\/histoere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nbi-ngf.ch\/wp-content\/uploads\/2026\/03\/Geschichte_nbi-ngf_2026_F-1.jpg","datePublished":"2025-07-16T04:45:34+00:00","dateModified":"2026-03-24T13:31:53+00:00","breadcrumb":{"@id":"https:\/\/www.nbi-ngf.ch\/fr\/a-propos-de-nous\/facts-figures\/histoere\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nbi-ngf.ch\/fr\/a-propos-de-nous\/facts-figures\/histoere\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.nbi-ngf.ch\/fr\/a-propos-de-nous\/facts-figures\/histoere\/#primaryimage","url":"https:\/\/www.nbi-ngf.ch\/wp-content\/uploads\/2026\/03\/Geschichte_nbi-ngf_2026_F-1.jpg","contentUrl":"https:\/\/www.nbi-ngf.ch\/wp-content\/uploads\/2026\/03\/Geschichte_nbi-ngf_2026_F-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.nbi-ngf.ch\/fr\/a-propos-de-nous\/facts-figures\/histoere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nbi-ngf.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c0 propos de nous","item":"https:\/\/www.nbi-ngf.ch\/fr\/a-propos-de-nous\/"},{"@type":"ListItem","position":3,"name":"Facts &amp; Figures","item":"https:\/\/www.nbi-ngf.ch\/fr\/a-propos-de-nous\/facts-figures\/"},{"@type":"ListItem","position":4,"name":"Histoire"}]},{"@type":"WebSite","@id":"https:\/\/www.nbi-ngf.ch\/fr\/#website","url":"https:\/\/www.nbi-ngf.ch\/fr\/","name":"Nationales Versicherungsb\u00fcro | Nationaler Garantiefonds","description":"Schweiz","publisher":{"@id":"https:\/\/www.nbi-ngf.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nbi-ngf.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.nbi-ngf.ch\/fr\/#organization","name":"Nationales Versicherungsb\u00fcro | Nationaler Garantiefonds","url":"https:\/\/www.nbi-ngf.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.nbi-ngf.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.nbi-ngf.ch\/wp-content\/uploads\/2025\/04\/Logo-Nbi-Ngf.svg","contentUrl":"https:\/\/www.nbi-ngf.ch\/wp-content\/uploads\/2025\/04\/Logo-Nbi-Ngf.svg","caption":"Nationales Versicherungsb\u00fcro | Nationaler Garantiefonds"},"image":{"@id":"https:\/\/www.nbi-ngf.ch\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.nbi-ngf.ch\/fr\/wp-json\/wp\/v2\/pages\/3684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nbi-ngf.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.nbi-ngf.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.nbi-ngf.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nbi-ngf.ch\/fr\/wp-json\/wp\/v2\/comments?post=3684"}],"version-history":[{"count":83,"href":"https:\/\/www.nbi-ngf.ch\/fr\/wp-json\/wp\/v2\/pages\/3684\/revisions"}],"predecessor-version":[{"id":8839,"href":"https:\/\/www.nbi-ngf.ch\/fr\/wp-json\/wp\/v2\/pages\/3684\/revisions\/8839"}],"up":[{"embeddable":true,"href":"https:\/\/www.nbi-ngf.ch\/fr\/wp-json\/wp\/v2\/pages\/3620"}],"wp:attachment":[{"href":"https:\/\/www.nbi-ngf.ch\/fr\/wp-json\/wp\/v2\/media?parent=3684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}